{"id":6800,"date":"2022-06-17T12:43:26","date_gmt":"2022-06-17T10:43:26","guid":{"rendered":"https:\/\/www.dreamyachtcharter.com\/destination\/location-de-bateaux-et-catamarans-a-la-paz"},"modified":"2026-03-23T10:32:41","modified_gmt":"2026-03-23T09:32:41","slug":"la-paz","status":"publish","type":"destination","link":"https:\/\/www.dreamyachtcharter.com\/fr\/destinations\/la-paz\/","title":{"rendered":"Location de bateaux et voiliers \u00e0 La Paz"},"content":{"rendered":"\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile\">\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1.jpg\" alt=\"La Paz\" class=\"wp-image-35753\" srcset=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1.jpg 1920w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1-1536x1024.jpg 1536w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1-1272x848.jpg 1272w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1-912x608.jpg 912w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1-672x448.jpg 672w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1-514x343.jpg 514w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_09-1-424x283.jpg 424w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<p>La Paz est situ\u00e9e \u00e0 l&rsquo;extr\u00e9mit\u00e9 sud de la p\u00e9ninsule de Basse Californie, s\u00e9par\u00e9e du Mexique par la fascinante mer de Cortez, \u00e9galement connue sous le nom de golfe de Californie. Cette mer, qui a un statut l\u00e9gendaire parmi les plongeurs et les p\u00eacheurs sportifs, est le choix id\u00e9al pour des vacances \u00e0 la voile authentiques dans des d\u00e9cors pr\u00e9serv\u00e9s.<\/p>\n\n\n\n<p>Vous d\u00e9couvrirez lors de votre croisi\u00e8re en bateau \u00e0 La Paz de paisibles criques de couleur turquoise, des d\u00e9serts immacul\u00e9s et des cha\u00eenes de montagnes accident\u00e9es, ainsi que de magnifiques mouillages \u00e0 distance sur plus de 100&nbsp;miles de c\u00f4te.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile\">\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<p>Naviguez jusqu&rsquo;\u00e0 Isla San Francisco, un mouillage populaire dans une baie en forme de croissant bord\u00e9e de plages de sable blanc, de falaises rouges et d&rsquo;eaux cristallines. Cette crique sublime offre de belles possibilit\u00e9s de randonn\u00e9e, de snorkeling et de p\u00eache. <\/p>\n\n\n\n<p>Vous pouvez \u00e9galement aller observer de pr\u00e8s les baleines ou les dauphins. Ou encore nager avec les otaries dans l&rsquo;aquarium naturel de l&rsquo;Isla Espiritu Santo. <\/p>\n\n\n\n<p>Notre base pour vos vacances \u00e0 la voile est situ\u00e9e dans la superbe marina Costa Baja \u00e0 La Paz, o\u00f9 vous trouverez \u00e9galement des stations baln\u00e9aires de luxe, des terrains de golf, des restaurants raffin\u00e9s, des mus\u00e9es et des b\u00e2timents de l&rsquo;\u00e9poque coloniale restaur\u00e9s. Tout cela fait de La Paz une destination inoubliable.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Sailing Vacation Sea of Cortez, La Paz, Mexico | Dream Yacht Charter\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/4Sru_oAqv5g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<div class=\"bg-light-gold is-reach-out py-pattern-38 \">\n\t<div class=\"container\">\n\t\t<div class=\"wrapper\">\n\t\t\t\t\t\t\n\n<h2 class=\"wp-block-heading has-text-align-center mb-2\" id=\"act\">Choisissez un type de location ci-dessous pour voir les bateaux disponibles<\/h2>\n\n\n\n<div class=\"bg-light-gold is-reach-out py-pattern-38 available-charter-types my-pattern-68\">\n    <div class=\"container\">\n        <p class=\"has-text-align-center mb-6\"><\/p>\n        <div class=\"grid-4 mb-pattern-68 set-parent-reach_out-bg-color bg-golden_hour\">\n                                <div>\n                        \n<div class=\"card card--hover card--border card--charter-type w-100p\">\n\t<div class=\"card__content\">\n\t\t<div class=\"card__content--icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--boat-type icon--48 card__icon text-brown\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-boat-type\"><\/use>\n\t\t\t<\/svg>\t\t<\/div>\n\t\t<div class=\"card__content--content\">\n\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\tSans \u00e9quipage\t\t\t<\/h3>\n\t\t\t<div class=\"editor text-primary mb-1\">\n\t\t\t\tPour les navigateurs exp\u00e9riment\u00e9s, une croisi\u00e8re en bateau sans \u00e9quipage est l&rsquo;escapade id\u00e9ale.\t\t\t<\/div>\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/charter\/location-bateau-sans-skipper\/la-paz\/\"\n                   class=\"push push--tertiary stretched-link px-0 text-brown added_currency\">Voir<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n                    <\/div>\n                                        <div>\n                        \n<div class=\"card card--hover card--border card--charter-type w-100p\">\n\t<div class=\"card__content\">\n\t\t<div class=\"card__content--icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--skippered icon--48 card__icon text-brown\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-skippered\"><\/use>\n\t\t\t<\/svg>\t\t<\/div>\n\t\t<div class=\"card__content--content\">\n\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\tAvec skipper\t\t\t<\/h3>\n\t\t\t<div class=\"editor text-primary mb-1\">\n\t\t\t\tD\u00e9tendez-vous et confiez la navigation \u00e0 un skipper professionnel.\t\t\t<\/div>\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/charter\/location-bateau-avec-skipper\/la-paz\/\"\n                   class=\"push push--tertiary stretched-link px-0 text-brown added_currency\">Voir<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n                    <\/div>\n                                        <div>\n                        \n<div class=\"card card--hover card--border card--charter-type w-100p\">\n\t<div class=\"card__content\">\n\t\t<div class=\"card__content--icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--easy-crewed icon--48 card__icon text-brown\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-easy-crewed\"><\/use>\n\t\t\t<\/svg>\t\t<\/div>\n\t\t<div class=\"card__content--content\">\n\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\tAvec \u00e9quipage\t\t\t<\/h3>\n\t\t\t<div class=\"editor text-primary mb-1\">\n\t\t\t\tLe moyen le plus simple et sans souci de louer un bateau priv\u00e9 avec \u00e9quipage. \t\t\t<\/div>\n\t\t\t\t\t\t\t<a href=\"#\"\n                   class=\"push push--tertiary stretched-link px-0 text-brown added_currency\">Voir<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n                    <\/div>\n                                        <div>\n                        \n<div class=\"card card--hover card--border card--charter-type w-100p is-disabled\">\n\t<div class=\"card__content\">\n\t\t<div class=\"card__content--icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--cabin-cruise icon--48 card__icon text-brown\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-cabin-cruise\"><\/use>\n\t\t\t<\/svg>\t\t<\/div>\n\t\t<div class=\"card__content--content\">\n\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\tCroisi\u00e8re \u00e0 la cabine\t\t\t<\/h3>\n\t\t\t<div class=\"editor text-primary mb-1\">\n\t\t\t\tR\u00e9servez une cabine avec salle d&rsquo;eau privative sur un catamaran moderne. \t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n                    <\/div>\n                                        <div>\n                        \n<div class=\"card card--hover card--border card--charter-type w-100p is-disabled\">\n\t<div class=\"card__content\">\n\t\t<div class=\"card__content--icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--sail-share icon--48 card__icon text-brown\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-sail-share\"><\/use>\n\t\t\t<\/svg>\t\t<\/div>\n\t\t<div class=\"card__content--content\">\n\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\tSailShare\t\t\t<\/h3>\n\t\t\t<div class=\"editor text-primary mb-1\">\n\t\t\t\tTarifs forfaitaires avantageux pour une excursion sociale d\u2019\u00eele en \u00eele \u00e0 bord d\u2019un voilier.\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n                    <\/div>\n                                        <div>\n                        \n<div class=\"card card--hover card--border card--charter-type w-100p is-disabled\">\n\t<div class=\"card__content\">\n\t\t<div class=\"card__content--icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--bareboat icon--48 card__icon text-brown\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-bareboat\"><\/use>\n\t\t\t<\/svg>\t\t<\/div>\n\t\t<div class=\"card__content--content\">\n\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\tBateaux \u00e0 moteur\t\t\t<\/h3>\n\t\t\t<div class=\"editor text-primary mb-1\">\n\t\t\t\tNaviguez et voyez plus loin \u00e0 bord du parfait bateau \u00e0 moteur.\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n                    <\/div>\n                            <\/div>\n                            <div class=\"d-flex justify-content-center\">\n                <a class=\"push push--normal push--primary_white_dark\" href=\"https:\/\/www.dreamyachtcharter.com\/fr\/charters\/\" id=\"linkShortCodeCharterTypes\">En savoir plus sur les types de location<\/a>\n            <\/div>\n        \n    <\/div>\n<\/div>\n\n\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"dyc-toggle \">\n\t\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<h2 class=\"wp-block-heading text-md-center\" id=\"things-to-do\">Que faire \u00e0 La Paz&nbsp;?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/A_la_paz_yacht_charter_07-1024x439.jpg\" alt=\"Vacances \u00e0 la voile \u00e0 La Paz, rochers et mer\" class=\"wp-image-336\"\/><\/figure>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading scale-7 font-medium mb-1\">Nagez avec les otaries<\/h3>\n\n\n\n<p>L&rsquo;une des choses les plus passionnantes \u00e0 faire \u00e0 La Paz est de mettre le cap sur la magnifique \u00eele d&rsquo;Espiritu Santo et d&rsquo;y rejoindre un guide certifi\u00e9 pour faire du snorkeling et nager avec des otaries curieuses et joueuses. Vous y profiterez d&rsquo;un d\u00e9cor magnifique d&rsquo;\u00eeles de roches rouges accident\u00e9es, d&rsquo;oiseaux et de vie marine.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading scale-7 font-medium mb-1\">Randonn\u00e9e \u00e0 Isla San Francisco<\/h3>\n\n\n\n<p>Promenez-vous sur la cr\u00eate qui vous m\u00e8nera au sommet des collines entourant cette sublime baie en forme de croissant. N&rsquo;oubliez pas votre appareil photo pour capturer les contrastes du ciel, de la mer, du sable et de la roche. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading scale-7 font-medium mb-1\">Flanez sur la promenade Malecon<\/h3>\n\n\n\n<p>Assurez-vous de visiter le pittoresque front de mer Paseo Alvaro Obregon lors de vos vacances \u00e0 la voile \u00e0 La Paz. Flanez dans les boutiques le long de la promenade Malecon et admirez les magnifiques statues qui la bordent. Le soir, profitez d&rsquo;un superbe coucher de soleil et go\u00fbtez aux d\u00e9lices locaux des stands de cuisine de rue.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading scale-7 font-medium mb-1\">Snorkeling \u00e0 Isla Espiritu Santo<\/h3>\n\n\n\n<p>Ne manquez pas d&rsquo;explorer Cardenal et Candelero sur Isla Espiritu Santo. Ils vous offriront des aventures de snorkeling dans des eaux transparentes. Profitez d&rsquo;un pique-nique en bord de mer apr\u00e8s votre baignade.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading scale-7 font-medium mb-1\">Observez les requins-baleines en migration<\/h3>\n\n\n\n<p>Les requins-baleines g\u00e9ants mais pacifiques de La Paz se nourrissent \u00e0 travers un filtre dans leur large bouche et sont sans danger pour les baigneurs. Cette exp\u00e9rience unique et exaltante est hautement r\u00e9glement\u00e9e afin de prot\u00e9ger les animaux. Vous devez donc la r\u00e9server aupr\u00e8s d&rsquo;un voyagiste local agr\u00e9\u00e9. C&rsquo;est l&rsquo;une des plus belles activit\u00e9s offertes par La Paz, alors ne la manquez pas&nbsp;!<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column\"><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<\/div>\n\n\n<div class=\"dyc-toggle \">\n\t\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"weather-insights\">Conditions climatiques<\/h2>\n\n\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile\">\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_08-1024x683.jpg\" alt=\"Vacances \u00e0 la voile dans les eaux cristallines de La Paz\" class=\"wp-image-342\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<h3 class=\"wp-block-heading\">Quel est le meilleur moment pour aller \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>La meilleure p\u00e9riode de l&rsquo;ann\u00e9e pour naviguer \u00e0 La Paz est de mi-f\u00e9vrier \u00e0 fin juin ou de mi-octobre \u00e0 fin d\u00e9cembre. <\/p>\n\n\n\n<p>\u00c0 La Paz, les \u00e9t\u00e9s sont longs et chauds, tandis que les hivers sont courts, agr\u00e9ables et secs. Les temp\u00e9ratures \u00e0 La Paz en \u00e9t\u00e9 atteignent en moyenne 32&nbsp;\u00b0C en mai et en octobre, allant parfois jusqu&rsquo;\u00e0 38&nbsp;\u00b0C. Vous pourrez \u00e9galement profiter de fantastiques temp\u00e9ratures en mer de plus de 26&nbsp;\u00b0C.<\/p>\n\n\n\n<p>Il fait plus sec en basse saison entre d\u00e9cembre et f\u00e9vrier, o\u00f9 les temp\u00e9ratures restent agr\u00e9ables, 26&nbsp;\u00b0C en moyenne. \u00c0 La Paz, environ 90&nbsp;% des pluies tombent entre juillet et octobre. <\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns is-not-stacked-on-mobile\">\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<h3 class=\"wp-block-heading\">Quelles sont les conditions de navigation \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>Les conditions de navigation comprennent des vents du sud dont la vitesse moyenne est de 10 \u00e0 15&nbsp;n\u0153uds. La plupart des temp\u00eates tropicales du bassin du Pacifique pendant la saison des ouragans passent g\u00e9n\u00e9ralement au sud de La Paz et de la pointe sud de la p\u00e9ninsule de Baja.<\/p>\n\n\n\n<p> Vous devrez aller voir le capitaine de port et lui laisser un plan de voyage d\u00e9taill\u00e9 avant de quitter la marina, dont la destination pr\u00e9vue et des informations sur l&rsquo;\u00e9quipage et les passagers.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/B_la_paz_yacht_charter_11-1024x683.jpg\" alt=\"Habitants de La Paz profitant de vacances sur un catamaran avec skipper \" class=\"wp-image-348\"\/><\/figure>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<\/div>\n\n\n<div class=\"dyc-toggle \">\n\t\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<h2 class=\"wp-block-heading text-md-center\">Naviguez \u00e0 La Paz avec Dream Yacht<\/h2>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading\">Bateaux et catamarans \u00e0 La Paz<\/h3>\n\n\n\n<p>En louant un bateau La Paz, au Mexique, vous pourrez profiter du meilleur de la mer de Cortez et naviguer autour de ses \u00eeles. Choisissez parmi nos catamarans et nos monocoques. <\/p>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button is-style-push-tertiary\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/fr\/charter\/location-bateau-sans-skipper\/la-paz\/\">En savoir plus<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading\">Locations de bateaux et catamarans avec skipper \u00e0 La Paz<\/h3>\n\n\n\n<p>Vous n&rsquo;avez pas besoin d&rsquo;exp\u00e9rience de navigation pour profiter de vacances \u00e0 la voile sur la mer de Cortez. Louez les services d&rsquo;un skipper sur votre bateau. Il vous fera naviguer autour des plus beaux endroits de La Paz pendant que vous vous d\u00e9tendrez.<\/p>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button is-style-push-tertiary\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/fr\/charter\/location-bateau-avec-skipper\/la-paz\/\">En savoir plus<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large mt-pattern-56\"><img decoding=\"async\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/A_la_paz_yacht_charter_06-1024x439.jpg\" alt=\"Bateau avec skipper \u00e0 La Paz sur une mer magnifique\" class=\"wp-image-354\"\/><\/figure>\n<\/div><\/div>\n\n\n<\/div>\n\n\n<div class=\"dyc-toggle \">\n\t\n<div class=\"bg-light-grey is-reach-out py-pattern-38 \">\n\t<div class=\"container\">\n\t\t<div class=\"wrapper\">\n\t\t\t\t\t\t\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"itinerary\">Itin\u00e9raire de voile \u00e0 La Paz<\/h2>\n\n\n\n<p class=\"has-text-align-left mb-pattern-56 text-md-center\">Consultez nos suggestions de vacances \u00e0 la voile \u00e0 La Paz<\/p>\n\n\n    <div class=\"itinerary accordion-container\">\n                    <div class=\"ac itinerary__one\">\n                <div class=\"ac-header\">\n                    <div class=\"ac-trigger itinerary__trigger\">\n                                                <span class=\"scale-5 text-primary\">\n                            La Paz 7 jours                        <\/span>\n                        <svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>                    <\/div>\n                <\/div>\n                <div class=\"ac-panel\">\n                    <div class=\"ac-text text-primary\">\n                        <iframe loading=\"lazy\"\n                            style=\"height: 80vh;\"\n                            height=\"100%\" width=\"100%\"\n                            src=\"https:\/\/charteritinerary.com\/shared\/dd67e8a8184a888af7dcee3710030eed\"\n                            width=\"100%\" height=\"800\" frameborder=\"0\"><\/iframe>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n    <div class=\"itinerary accordion-container additional\" style=\"margin-top: 40px;\">\n\n        <div class=\"ac itinerary__two\">\n            <div class=\"ac-header\">\n                <div class=\"ac-trigger itinerary__trigger title\">\n                    <span class=\"scale-7 text-primary font-normal title\">\n                        Autres itin\u00e9raires                    <\/span>\n                    <svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>                <\/div>\n            <\/div>\n            <div class=\"ac-panel\">\n                <div class=\"itinerary accordion-container\">\n                                            <div class=\"ac itinerary__one\">\n                            <div class=\"ac-header\">\n                                <div class=\"ac-trigger itinerary__trigger\">\n                                                                        <span class=\"scale-6 text-primary\">\n                                        Itin\u00e9raire de 7 jours \u00e0 la Paz, Mexique                                    <\/span>\n                                    <svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>                                <\/div>\n                            <\/div>\n                            <div class=\"ac-panel\">\n                                <div class=\"ac-text text-primary\">\n                                    <div class=\"swiper slider--part\">\n                                        <div class=\"swiper-wrapper\">\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;1&nbsp;: Ensenada Grande<\/h3>\n                                                            <p>Mettez le cap sur Ensenada Grande, un mouillage populaire pour ses eaux couleur turquoise, ses falaises rocheuses imposantes et ses plages de sable blanc. \u00c0 terre, vous pouvez faire de la randonn\u00e9e, vous d\u00e9tendre sur la plage ou vous baigner et faire du snorkeling le long du littoral rocheux.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;2&nbsp;: Los Islotes &#8211; El Bajito &#8211; San Evaristo<\/h3>\n                                                            <p>Situ\u00e9s juste \u00e0 c\u00f4t\u00e9 de la pointe nord-ouest d&#039;Isla Partida, les \u00eelots rocheux connus sous le nom de Los Islotes sont c\u00e9l\u00e8bres pour \u00eatre l&#039;un des rares endroits o\u00f9 vous pouvez nager avec les otaries dans un cadre naturel. Amarrez les d\u00e9riveurs aux bou\u00e9es du Parc National sur les rives nord et sud. Dirigez-vous vers El Bajito pour une exaltante plong\u00e9e au milieu de poissons tropicaux ou mettez le cap sur San Evaristo, un village de p\u00eacheurs pittoresque, pour passer la nuit dans un mouillage bien prot\u00e9g\u00e9.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;3&nbsp;: Isla San Francisco<\/h3>\n                                                            <p>Naviguez jusqu&#039;\u00e0 Isla San Francisco, un mouillage populaire dans une baie en forme de croissant bord\u00e9e de plages de sable blanc, de falaises rouges et d&#039;eaux cristallines. Cette magnifique crique offre de fantastiques possibilit\u00e9s de randonn\u00e9e, de snorkeling, de p\u00eache et de d\u00e9tente \u00e0 la plage. La vaste baie peut accueillir de nombreux bateaux et offre une bonne r\u00e9sistance au mouillage.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;4&nbsp;: Amortajada<\/h3>\n                                                            <p>Dirigez-vous vers Amortajada, sur la pointe sud-ouest d&#039;Isla San Jose. Lorsque vous atteignez l&#039;ancrage, mettez votre d\u00e9riveur ou votre kayak \u00e0 l&#039;eau pour explorer le lagon principal en traversant les mangroves. Prenez vos jumelles pour observer les aigrettes et les h\u00e9rons.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;5&nbsp;: Espiritu Santo &#8211; Bahia San Gabriel &#8211; Punta Prieta &#8211; Ensenada de la Dispensa<\/h3>\n                                                            <p>Mettez le cap sur Isla Espiritu Santo et la plus belle plage de la baie de Bahia San Gabriel. Dirigez-vous vers la c\u00f4te ouest rocheuse de Punta Prieta et la pointe sud d&#039;Ensenada de la Dispensa pour une fantastique exp\u00e9rience de snorkeling.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;6&nbsp;: Puerto Balandra<\/h3>\n                                                            <p>Prenez la direction de Puerto Balandra, ses huit plages de sable blanc immacul\u00e9 et son lagon sal\u00e9 int\u00e9rieur qui abrite la formation rocheuse \u00ab&nbsp;El Hongo&nbsp;\u00bb, \u00e9galement connu sous le nom de champignon. Vous trouverez dans les eaux bleues scintillantes une multitude de poissons et de coraux aux couleurs vives qui raviront les nageurs et les plongeurs.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;7&nbsp;: navigation<\/h3>\n                                                            <p>Retournez \u00e0 la base pour y \u00eatre \u00e0 10h.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                    <\/div>\n                                        <div class=\"swiper-pagination\"><\/div>\n                                        <div class=\"swiper-buttons\">\n                                            <div class=\"swiper-button-prev\">\n                                                <svg aria-hidden=\"true\" class=\"icon icon--arrow-left icon--16\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-arrow-left\"><\/use>\n\t\t\t<\/svg>                                            <\/div>\n                                            <div class=\"swiper-button-next\">\n                                                <svg aria-hidden=\"true\" class=\"icon icon--arrow-right icon--16\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-arrow-right\"><\/use>\n\t\t\t<\/svg>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                            <div class=\"ac itinerary__one\">\n                            <div class=\"ac-header\">\n                                <div class=\"ac-trigger itinerary__trigger\">\n                                                                        <span class=\"scale-6 text-primary\">\n                                        Itin\u00e9raire de 14 jours \u00e0 la Paz, Mexique                                    <\/span>\n                                    <svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>                                <\/div>\n                            <\/div>\n                            <div class=\"ac-panel\">\n                                <div class=\"ac-text text-primary\">\n                                    <div class=\"swiper slider--part\">\n                                        <div class=\"swiper-wrapper\">\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;1&nbsp;: \u00eele d&#039;Espiritu Santo<\/h3>\n                                                            <p>Commencez votre croisi\u00e8re en explorant des paysages sous-marins \u00e0 couper le souffle&nbsp;: faites du snorkeling sur la c\u00f4te ouest rocheuse d&#039;Isla Espiritu Santo \u00e0 Punta Prieta ou \u00e0 la pointe sud, \u00e0 Ensenada de la Dispensa. Jetez l&#039;ancre \u00e0 Caleta Partida ou \u00e0 Ensenada Grande pour y passer la nuit et vous d\u00e9tendre.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;2&nbsp;: Los Islotes &#8211; Isla Partida &#8211; El Bajito &#8211; San Evaristo<\/h3>\n                                                            <p>Nagez avec des otaries dans leur habitat naturel en mettant le cap sur Los Islotes \u00e0 la pointe nord-ouest d&#039;Isla Partida. Vous pouvez amarrer votre d\u00e9riveur aux bou\u00e9es du Parc National sur les rives nord et sud de l&#039;\u00eele. Au sud-ouest, plongez au milieu des poissons tropicaux \u00e0 El Bajito, puis dirigez-vous vers San Evaristo, un village de p\u00eacheurs pittoresque, pour passer la nuit \u00e0 un mouillage prot\u00e9g\u00e9.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;3&nbsp;: Nopolo<\/h3>\n                                                            <p>Naviguez vers Nopolo, jetez l&#039;ancre vous dans les lobes nord ou sud de Nopolo et partez en annexe explorer des villages de p\u00eacheurs isol\u00e9s. Vous serez prot\u00e9g\u00e9s des vents du nord et libres ainsi d&#039;explorer cette retraite tranquille.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;4&nbsp;: Puerto de Gato<\/h3>\n                                                            <p>Dirigez-vous vers Puerto de Gato. Son ancrage est un peu limit\u00e9, mais vous y trouverez de superbes plong\u00e9es et activit\u00e9s de snorkeling \u00e0 faire au milieu de formations rocheuses rouges et de plages de sable blanc.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;5&nbsp;: Bahia Agua Verde &#8211; Puerto Escondido<\/h3>\n                                                            <p>Profitez d&#039;un vaste mouillage, d\u00e9couvrez des peintures rupestres et faites du snorkeling \u00e0 Bahia Agua Verde, village de p\u00eacheurs isol\u00e9. Vous pourrez passer la nuit \u00e0 Puerto Escondido, qui est \u00e0 proximit\u00e9. Faites-y le plein d&#039;eau et de carburant. Vous pouvez faire vos courses \u00e0 Loreto, \u00e0 seulement quelques minutes en taxi.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;6&nbsp;: \u00eele de Carmen &#8211; \u00eele Danzante &#8211; Bahia Agua Verde<\/h3>\n                                                            <p>Pr\u00e9voyez une visite \u00e0 la pointe sud de l&#039;\u00eele de Carmen ainsi que sur l&#039;\u00eele Danzante. Apr\u00e8s une journ\u00e9e bien charg\u00e9e, retournez \u00e0 Bahia Agua Verde pour la nuit.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;7&nbsp;: San Cosme &#8211; Puerto Los Gatos<\/h3>\n                                                            <p>Apr\u00e8s un petit-d\u00e9jeuner copieux, faites route vers l&#039;\u00eele de San Cosme pour y passer la journ\u00e9e. Mettez le cap sur le sud pour passer la nuit \u00e0 Puerto Los Gatos, o\u00f9 vous serez prot\u00e9g\u00e9s des vents du nord-ouest.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;8&nbsp;: Amortajada<\/h3>\n                                                            <p>Mettez le cap sur le mouillage d&#039;Amortajada, \u00e0 l&#039;extr\u00e9mit\u00e9 sud-ouest d&#039;Isla San Jose. Observez les aigrettes et les h\u00e9rons lorsque vous traversez les mangroves en kayak jusqu&#039;au lagon principal.\r\n<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;9&nbsp;: Isla San Francisco<\/h3>\n                                                            <p>D\u00e9couvrez l&#039;anse idyllique d&#039;Isla San Francisco aux plages de sable blanc sur fond de mer scintillante et aux rivages bord\u00e9s de rochers rouges. Ce mouillage tr\u00e8s pris\u00e9 offre certaines des meilleures activit\u00e9s de randonn\u00e9e, de snorkeling et de p\u00eache de la r\u00e9gion, ainsi que des plages parmi les plus belles. Bien qu&#039;elle soit tr\u00e8s populaire, la baie peut accueillir de nombreux bateaux et offre une bonne r\u00e9sistance au mouillage.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;10&nbsp;: Ensenada Grande &#8211; \u00eele d&#039;Espiritu Santo<\/h3>\n                                                            <p>Apr\u00e8s le lever du soleil, naviguez jusqu&#039;\u00e0 Ensenada Grande pour nager dans ses eaux turquoises ou vous promener sur ses plages de sable blanc. Explorez son littoral rocheux sous l&#039;eau ou faites de la randonn\u00e9e sur la terre ferme. Sur Isla Espiritu Santo, vous trouverez un sentier \u00e0 l&#039;extr\u00e9mit\u00e9 sud de la plage de Bahia San Gabriel qui vous m\u00e8nera \u00e0 un autre paradis de sable blanc.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;11&nbsp;: Cardenal &#8211; Candelero<\/h3>\n                                                            <p>Ne manquez pas d&#039;explorer Cardenal et Candelero sur Isla Espiritu Santo. Vous y trouverez des aventures de snorkeling dans des eaux transparentes. Il sera ensuite temps de retourner passer une autre nuit \u00e0 Ensenada Grande.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;12&nbsp;: Puerto Ballena &#8211; \u00eele Ballena &#8211; \u00eele Gallo &#8211; \u00eele Gallina<\/h3>\n                                                            <p>Naviguez autour de Puerto Ballena et faites des arr\u00eats sur l&#039;\u00eele Ballena, l&#039;\u00eele Gallo et l&#039;\u00eele Gallina, toutes situ\u00e9es dans des eaux turquoise bien prot\u00e9g\u00e9es.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;13&nbsp;: Puerto Balandra<\/h3>\n                                                            <p>Offrant lui aussi une plage de sable blanc et une eau bleue chatoyante, Puerto Balandra est un merveilleux terrain de jeu pour tout plongeur, randonneur ou kayakiste. Il abrite \u00e9galement la c\u00e9l\u00e8bre formation rocheuse en forme de champignon \u00ab&nbsp;El Hongo&nbsp;\u00bb et un lagon sal\u00e9 int\u00e9rieur.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                                <div class=\"swiper-slide\">\n                                                        <div>\n                                                            <h3 class=\"scale-6 mb-3 font-normal\">Jour&nbsp;14&nbsp;: navigation<\/h3>\n                                                            <p>Retournez \u00e0 la base.<\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                                                    <\/div>\n                                        <div class=\"swiper-pagination\"><\/div>\n                                        <div class=\"swiper-buttons\">\n                                            <div class=\"swiper-button-prev\">\n                                                <svg aria-hidden=\"true\" class=\"icon icon--arrow-left icon--16\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-arrow-left\"><\/use>\n\t\t\t<\/svg>                                            <\/div>\n                                            <div class=\"swiper-button-next\">\n                                                <svg aria-hidden=\"true\" class=\"icon icon--arrow-right icon--16\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-arrow-right\"><\/use>\n\t\t\t<\/svg>                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<\/div>\n\n\n<div class=\"dyc-toggle \">\n\t\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<h2 class=\"wp-block-heading text-md-center\">Informations utiles pour les locations de bateaux et catamarans \u00e0 La Paz<\/h2>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<figure class=\"wp-block-image size-large js-fix-image\"><img decoding=\"async\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/06\/C_la_paz_yacht_charter_17-1024x1024.jpg\" alt=\"P\u00eache \u00e0 La Paz et d\u00e9tente sur un bateau de location\" class=\"wp-image-372\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Se rendre \u00e0 La Paz depuis l&rsquo;Europe<\/h3>\n\n\n\n<p>Le moyen le plus pratique pour rejoindre notre base et commencer vos vacances \u00e0 la voile est de prendre l&rsquo;avion pour l&rsquo;a\u00e9roport international de La Paz (LAP). AeroMexico propose le plus de vols et il y a plusieurs autres compagnies a\u00e9riennes qui transitent via Los Angeles (LAX) ou Mexico.<\/p>\n\n\n\n<p>L&rsquo;a\u00e9roport de La Paz est accessible en 30&nbsp;minutes en taxi. Nous pouvons organiser un transfert \u00e0 l&rsquo;arriv\u00e9e \u00e0 l&rsquo;a\u00e9roport sur demande. <\/p>\n\n\n\n<p>Vous pouvez \u00e9galement vous rendre \u00e0 La Paz via l&rsquo;a\u00e9roport international de Los Cabos (SJD), mais le transfert prend entre 2h30 et 3h, via une navette ou un taxi priv\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quelle langue parle-t-on \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>La langue parl\u00e9e \u00e0 La Paz est l&rsquo;espagnol.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quelle est la devise utilis\u00e9e \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>La devise utilis\u00e9e \u00e0 La Paz est le peso mexicain (MXN), mais les dollars am\u00e9ricains sont accept\u00e9s dans les principales zones touristiques.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quelles sont les restrictions douani\u00e8res pour La Paz&nbsp;?<\/h3>\n\n\n\n<p>Vous pouvez consulter les informations douani\u00e8res sur le site web <a href=\"https:\/\/www.gob.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">gob.mx<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">De quels documents ai-je besoin pour naviguer \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>Les citoyens fran\u00e7ais doivent \u00eatre munis d&rsquo;un passeport en cours de validit\u00e9. <\/p>\n\n\n\n<p>Ils ne sont pas soumis \u00e0 l\u2019obligation de visa de court s\u00e9jour pour entrer au Mexique dans le cadre d\u2019un voyage touristique, qui ne peut n\u00e9anmoins pas d\u00e9passer 180 jours. Nous vous conseillons de contacter votre ambassade pour en savoir plus. <\/p>\n\n\n\n<p>Les citoyens mexicains auront besoin d&rsquo;un permis bateau pour faire de la voile au Mexique.<\/p>\n\n\n\n<p>Contactez-nous pour vous assurer d&rsquo;avoir les bons documents avant de partir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Comment puis-je me d\u00e9placer \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>Vous pouvez facilement h\u00e9ler un taxi-bus collectif avec sa destination affich\u00e9e sur le pare-brise. Si vous prenez un taxi, prenez soin de n\u00e9gocier le prix avant de monter. Il est judicieux de demander aux restaurants et aux bars de vous appeler un taxi pour vous ramener chez vous si vous sortez tard le soir lors de votre croisi\u00e8re en bateau au Mexique. <\/p>\n\n\n\n<p>Vous pouvez \u00e9galement louer une voiture, mais nous vous conseillons de faire votre r\u00e9servation \u00e0 l&rsquo;avance sur le site web de la soci\u00e9t\u00e9 afin d&rsquo;obtenir le meilleur prix.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quelle est l&rsquo;\u00e9tendue du r\u00e9seau wi-fi \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>Notre marina dispose d&rsquo;une connexion wi-fi gratuite. Le wi-fi \u00e0 La Paz est de bonne qualit\u00e9, et la plupart des villes et villages ont des points d&rsquo;acc\u00e8s wi-fi dans les bars et les restaurants. Il n&rsquo;y a pas de couverture t\u00e9l\u00e9phonique dans environ 70&nbsp;% de notre zone de navigation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quelles sont les r\u00e9glementations en vigueur \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>La navigation de nuit est interdite. Nous vous fournirons le permis d&rsquo;acc\u00e8s au parc requis pour visiter l&rsquo;\u00eele d&rsquo;Espiritu Santo. Toute personne qui p\u00eache \u00e0 partir d&rsquo;un bateau au Mexique aura besoin d&rsquo;un permis de p\u00eache d\u00e9livr\u00e9 par le gouvernement mexicain. Les permis de p\u00eache peuvent \u00eatre command\u00e9s en ligne.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">O\u00f9 puis-je trouver des pr\u00e9visions m\u00e9t\u00e9orologiques pour La Paz&nbsp;?<\/h3>\n\n\n\n<p>Vous trouverez des pr\u00e9visions m\u00e9t\u00e9orologiques sur le site web <a href=\"https:\/\/weather.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">weather.com<\/a>, avant et pendant votre location de bateau \u00e0 La Paz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quelles possibilit\u00e9s d&rsquo;avitaillement y a-t-il \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>Vous disposez d&rsquo;un grand choix d&rsquo;endroits pour faire votre avitaillement \u00e0 La Paz, dont le supermarch\u00e9 local Chedraui et Walmart. La base peut \u00e9galement fournir un service d&rsquo;avitaillement si vous souhaitez que vos courses soient pr\u00eates pour votre arriv\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quels bagages puis-je emporter pendant mes vacances \u00e0 la voile au Mexique&nbsp;?<\/h3>\n\n\n\n<p>Veuillez ne prendre que des sacs souples et non des valises car celles-ci sont trop encombrantes \u00e0 bord.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quel est le type de courant \u00e9lectrique \u00e0 La Paz&nbsp;?<\/h3>\n\n\n\n<p>Le courant \u00e9lectrique terrestre \u00e0 La Paz est de 110V.<\/p>\n\n\n\n<h3 class=\"wp-block-heading scale-7 mb-1 font-medium\">Quel est l&rsquo;indicatif t\u00e9l\u00e9phonique de La Paz&nbsp;?<\/h3>\n\n\n\n<p>L&rsquo;indicatif t\u00e9l\u00e9phonique de La Paz est le +52.<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n<\/div>\n\n\n<div class=\"dyc-toggle \">\n\t\n<div class=\"downloads is-reach-out dyc-section dyc-section--double bg-brown-light mt-0 mb-0 py-8\">\n\t<div class=\"container\">\n\t\t<h2 class=\"scale-0 font-normal text-dark-green mb-pattern-36 text-center\">T\u00e9l\u00e9chargements<\/h2>\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-12 col-md-8 offset-md-2\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"downloads__one bg-white mb-2\" href=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/nausys\/base_documents\/3642787\/BaseGuide_Bareboat_FR-6a97d2e05e6a1-LaPaz.pdf\" download>\n\t\t\t\t\t\t\t\t<div class=\"pt-1 pb-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"scale-7 font-normal text-dark-green d-block\">\n\t\t\t\t\t\t\t\t\t\tBase Guide Bareboat La Paz\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"text-dark-green text-uppercase font-normal scale-10\">\n\t\t\t\t\t\t\t\t\t\tpdf 1,05 Mo\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"downloads__one bg-white mb-2\" href=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/nausys\/base_documents\/3642787\/CrewList_Bareboat_FR-6a97d2e21e93b-LaPaz.doc\" download>\n\t\t\t\t\t\t\t\t<div class=\"pt-1 pb-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"scale-7 font-normal text-dark-green d-block\">\n\t\t\t\t\t\t\t\t\t\tCrew List Bareboat 12.doc\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"text-dark-green text-uppercase font-normal scale-10\">\n\t\t\t\t\t\t\t\t\t\tdoc 86,50 Ko\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"downloads__one bg-white mb-2\" href=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/nausys\/base_documents\/3642787\/CrewList_Crewed_FR-6a97d2e31a370-LaPaz.doc\" download>\n\t\t\t\t\t\t\t\t<div class=\"pt-1 pb-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"scale-7 font-normal text-dark-green d-block\">\n\t\t\t\t\t\t\t\t\t\tCrew List Crewed 10.doc\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"text-dark-green text-uppercase font-normal scale-10\">\n\t\t\t\t\t\t\t\t\t\tdoc 86,00 Ko\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"downloads__one bg-white mb-2\" href=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/nausys\/base_documents\/3642787\/PreferenceList_BBHostess_FR.07082026-6a97d2e6167df-LaPaz.pdf\" download>\n\t\t\t\t\t\t\t\t<div class=\"pt-1 pb-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"scale-7 font-normal text-dark-green d-block\">\n\t\t\t\t\t\t\t\t\t\tPreference List B B Hostess \t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"text-dark-green text-uppercase font-normal scale-10\">\n\t\t\t\t\t\t\t\t\t\tpdf 161,55 Ko\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"downloads__one bg-white mb-2\" href=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/nausys\/base_documents\/3642787\/PreferenceList_BB_CRW-6a97d2e7a022e-LaPaz.pdf\" download>\n\t\t\t\t\t\t\t\t<div class=\"pt-1 pb-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"scale-7 font-normal text-dark-green d-block\">\n\t\t\t\t\t\t\t\t\t\tPreference List B B F R.12012026.pdf\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"text-dark-green text-uppercase font-normal scale-10\">\n\t\t\t\t\t\t\t\t\t\tpdf 161,55 Ko\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"downloads__one bg-white mb-2\" href=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/nausys\/base_documents\/3642787\/PreferenceList_Skippered_FR.07082026-6a97d2e925055-LaPaz.pdf\" download>\n\t\t\t\t\t\t\t\t<div class=\"pt-1 pb-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"scale-7 font-normal text-dark-green d-block\">\n\t\t\t\t\t\t\t\t\t\tPreference List Skippered \t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"text-dark-green text-uppercase font-normal scale-10\">\n\t\t\t\t\t\t\t\t\t\tpdf 161,55 Ko\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"downloads__one bg-white mb-2\" href=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/nausys\/base_documents\/3642787\/SailingResume_Bareboat_FR-6a97d2eb57169-LaPaz.doc\" download>\n\t\t\t\t\t\t\t\t<div class=\"pt-1 pb-1\">\n\t\t\t\t\t\t\t\t\t<span class=\"scale-7 font-normal text-dark-green d-block\">\n\t\t\t\t\t\t\t\t\t\tSailing Resume Bareboat 1.doc\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"text-dark-green text-uppercase font-normal scale-10\">\n\t\t\t\t\t\t\t\t\t\tdoc 88,00 Ko\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<\/div>\n\n\n<div class=\"dyc-section text-center \">\n\t<a class=\"push push--secondary push--large push--icon d-inline-flex\" href=\"#act\">\n\t\tTypes de locations disponibles\t<\/a>\n<\/div>\n\n\n<div class=\"dyc-toggle \">\n\t\n\n<div class=\"dyc-section dyc-section--double is-reach-out py-4 py-md-8\">\n\t<div class=\"text-center mb-5 mb-md-6\"> \n\t\t<h2 class=\"scale-0 font-normal mb-2\">\n\t\t\tFAQ\t\t<\/h2>\n\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/questions-frequentes\/\" class=\"text-normal scale-8\">\n\t\t\t\tVoir notre FAQ\t\t\t<\/a>\n\t\t\t<\/div>\n\n\n\t<div class=\"row\">\n\t\t<div class=\"col-12 col-md-8 col-lg-8 offset-md-2 offset-lg-2\">\n\t\t\t\n<div class=\"accordion\">\n\t<div class=\"accordion-container p-max-100-chars p-max-100-center\">\n\t\t\t\t\t\t\t\t<div class=\"accordion__item ac mb-2\">\n\t\t\t\t<div class=\"ac-header\">\n\t\t\t\t\t<div class=\"ac-trigger\">\n\t\t\t\t\t\t<h3 class=\"ac-title scale-8 font-normal mr-2 mr-md-3\">\n\t\t\t\t\t\t\tPourquoi r\u00e9server avec Dream Yacht Worldwide?\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ac-panel\">\n\t\t\t\t\t<div class=\"ac-text\">\n\t\t\t\t\t\t<div class=\"editor\">\n\t\t\t\t\t\t\t\n<p>Dream Yacht Worldwide est aujourd\u2019hui le leader mondial de la location de bateaux et vous offre :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une flotte de plus de 800 yachts avec une grande vari\u00e9t\u00e9 de mod\u00e8les et de constructeurs pour s\u2019adapter \u00e0 tous les types de navigateurs.<\/li>\n\n\n\n<li>Nous avons plus de 35 destinations passionnantes et nous sommes pionniers dans la recherche de nouvelles zones de navigation.<\/li>\n\n\n\n<li>Vous pouvez \u00eatre assur\u00e9s de notre engagement envers l\u2019excellence du service \u00e0 la client\u00e8le<\/li>\n\n\n\n<li>Vous recevrez un accueil chaleureux et amical de la part de nos \u00e9quipes sur les bases, qui vous donneront des conseils, des recommandations et des astuces sur la r\u00e9gion.<\/li>\n\n\n\n<li>Nous sommes des vendeurs de bateaux neufs et d\u2019occasion de confiance et innovateurs dans les options de gestion de location \u2013 la voile est notre m\u00e9tier.<\/li>\n<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"accordion__item ac mb-2\">\n\t\t\t\t<div class=\"ac-header\">\n\t\t\t\t\t<div class=\"ac-trigger\">\n\t\t\t\t\t\t<h3 class=\"ac-title scale-8 font-normal mr-2 mr-md-3\">\n\t\t\t\t\t\t\tQuelles sont les licences dont j\u2019ai besoin pour louer un bateau et naviguer moi-m\u00eame ?\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ac-panel\">\n\t\t\t\t\t<div class=\"ac-text\">\n\t\t\t\t\t\t<div class=\"editor\">\n\t\t\t\t\t\t\t\n<p>Le skipper d\u2019un bateau est responsable de la s\u00e9curit\u00e9 de l\u2019\u00e9quipage et du bateau \u00e0 tout moment. De nombreuses destinations exigent simplement une exp\u00e9rience d\u00e9montr\u00e9e par un CV de navigation. <\/p>\n\n<p>Pour naviguer en M\u00e9diterran\u00e9e, vous devez \u00eatre titulaire d\u2019une licence de navigation reconnue par les autorit\u00e9s locales. Un permis de navigation est obligatoire pour les locations sans \u00e9quipage en Italie, Gr\u00e8ce, Su\u00e8de, Turquie, Croatie, Seychelles, Madagascar, Mont\u00e9n\u00e9gro, Br\u00e9sil, Tha\u00eflande et Espagne. Pour des navigations au Belize, une demande de certificat de comp\u00e9tence devra \u00eatre faite aux autorit\u00e9s portuaires.<\/p>\n\n<p>L\u2019original de votre permis doit \u00eatre embarqu\u00e9 avec vous sur votre bateau. Nous vous conseillons de contacter notre \u00e9quipe pour confirmer vos qualifications et les exigences de votre destination avant de r\u00e9server.<\/p>\n\n<p>En acceptant le contrat de location, vous confirmez que vous et\/ou les membres de votre \u00e9quipage sont comp\u00e9tents pour naviguer dans les conditions et la zone de croisi\u00e8re de votre location. Nous nous r\u00e9servons le droit de ne pas vous confier le bateau si, apr\u00e8s v\u00e9rification, nous estimons que le locataire n\u2019est pas ou peut ne pas \u00eatre comp\u00e9tent pour prendre en charge le bateau.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"accordion__item ac mb-2\">\n\t\t\t\t<div class=\"ac-header\">\n\t\t\t\t\t<div class=\"ac-trigger\">\n\t\t\t\t\t\t<h3 class=\"ac-title scale-8 font-normal mr-2 mr-md-3\">\n\t\t\t\t\t\t\tQu&rsquo;est-ce qu&rsquo;une location de bateau avec skipper&nbsp;?\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ac-panel\">\n\t\t\t\t\t<div class=\"ac-text\">\n\t\t\t\t\t\t<div class=\"editor\">\n\t\t\t\t\t\t\t\n<p>Une location de bateau avec skipper signifie que vous louez l&rsquo;un de nos bateaux pour vous et vos invit\u00e9s et qu&rsquo;un skipper professionnel le barre \u00e0 votre place. Aucune exp\u00e9rience de navigation n&rsquo;est n\u00e9cessaire.<\/p>\n\n<p>Vous devrez choisir un bateau qui dispose d&rsquo;une cabine r\u00e9serv\u00e9e \u00e0 votre skipper, car il est responsable de votre bateau pour la dur\u00e9e de votre location. Nous trouverons un skipper pour vous une fois que vous aurez trouv\u00e9 la destination et le bateau qui vous conviennent.<\/p>\n\n<p>Vous devrez payer la nourriture de votre skipper. Vous pouvez inviter le skipper \u00e0 d\u00eener avec vous \u00e0 bord ou dans un restaurant local.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"accordion__item ac mb-2\">\n\t\t\t\t<div class=\"ac-header\">\n\t\t\t\t\t<div class=\"ac-trigger\">\n\t\t\t\t\t\t<h3 class=\"ac-title scale-8 font-normal mr-2 mr-md-3\">\n\t\t\t\t\t\t\tQuelle est la diff\u00e9rence entre une croisi\u00e8re \u00e0 la cabine et la location avec \u00e9quipage tout compris ?\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ac-panel\">\n\t\t\t\t\t<div class=\"ac-text\">\n\t\t\t\t\t\t<div class=\"editor\">\n\t\t\t\t\t\t\t\n<p>Avec la cabine, vous n\u2019avez pas besoin de r\u00e9server tout le bateau et vous pouvez vous d\u00e9tendre pendant que l\u2019itin\u00e9raire est pris en charge. Vous n\u2019avez pas non plus \u00e0 vous pr\u00e9occuper du ravitaillement car il y a un menu fixe, qui est inclus. Vous voyagerez avec des clients partageant le m\u00eame plaisir du voyage.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"accordion__item ac mb-2\">\n\t\t\t\t<div class=\"ac-header\">\n\t\t\t\t\t<div class=\"ac-trigger\">\n\t\t\t\t\t\t<h3 class=\"ac-title scale-8 font-normal mr-2 mr-md-3\">\n\t\t\t\t\t\t\tPouvez-vous m\u2019en dire plus sur vos bateaux ?\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ac-panel\">\n\t\t\t\t\t<div class=\"ac-text\">\n\t\t\t\t\t\t<div class=\"editor\">\n\t\t\t\t\t\t\t\n<p>Tous nos bateaux avec \u00e9quipage r\u00e9pondent \u00e0 des normes \u00e9lev\u00e9es, sont spacieux et confortables. Ils font l\u2019objet d\u2019un entretien professionnel et sont r\u00e9guli\u00e8rement modernis\u00e9s. La flotte comprend de grands catamarans \u00e0 voile de 6 cabines.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"accordion__item ac mb-2\">\n\t\t\t\t<div class=\"ac-header\">\n\t\t\t\t\t<div class=\"ac-trigger\">\n\t\t\t\t\t\t<h3 class=\"ac-title scale-8 font-normal mr-2 mr-md-3\">\n\t\t\t\t\t\t\tAi-je besoin d\u2019une assurance pour ma location de bateau sans \u00e9quipage ?\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"icon icon--caret-down icon--24\">\n\t\t\t\t<use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#sprite-icon-caret-down\"><\/use>\n\t\t\t<\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ac-panel\">\n\t\t\t\t\t<div class=\"ac-text\">\n\t\t\t\t\t\t<div class=\"editor\">\n\t\t\t\t\t\t\t\n<p>Nous vous recommandons fortement de contracter une assurance voyage au cas o\u00f9 vous devriez annuler pour une raison inattendue, afin de couvrir les acomptes non remboursables. Assurez-vous d&rsquo;avoir une assurance voyage personnelle qui couvre la navigation.<\/p>\n\n<p>Nous assurerons le bateau contre tous les risques tout au long de la location aupr\u00e8s d&rsquo;assureurs de premi\u00e8re classe afin d&rsquo;autoriser la location conform\u00e9ment aux conditions contractuelles et de couvrir la responsabilit\u00e9 civile.<\/p>\n\n<p>Les options suivantes sont disponibles dans certaines destinations\u00a0:<\/p>\n\n<ul class=\"wp-block-list\"><li><p><strong>1 D\u00e9p\u00f4t de Garantie :<\/strong>\u00a0Cela varie en fonction de la taille du bateau et lorsque le bateau est rendu sans dommage, ce d\u00e9p\u00f4t (caution) est rembours\u00e9.<\/p><\/li><li><p><strong>2 Rachat de Franchise :<\/strong>\u00a0Le locataire s\u2019engage \u00e0 payer une franchise non remboursable au moment de la r\u00e9servation, ainsi qu\u2019une caution r\u00e9duite \u00e0 l\u2019embarquement, remboursable \u00e0 la fin de la location si aucun dommage ne survient.<\/p><\/li><\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<\/div>\n\n\n\n<div class=\"wp-block-group dyc-section dyc-section--banner\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<h2 class=\"mb-3 wp-block-heading\">Avez-vous d\u00e9j\u00e0 envisag\u00e9 une croisi\u00e8re en cabine ?<\/h2>\n\n\n\n<p>En tant que pionnier de l&rsquo;industrie, Dream Yacht a \u00e9t\u00e9 l&rsquo;un des premiers \u00e0 d\u00e9velopper le concept de croisi\u00e8res \u00e0 la cabine. C&rsquo;est un choix id\u00e9al pour les voyageurs solo ou en couple \u00e0 la recherche d&rsquo;aventures d\u00e9tendues, de destinations exotiques et de cultures locales uniques dans un cadre intime et social &#8211; dans le confort en mer.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button is-style-push-primary\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.dreamyachtcharter.com\/fr\/charters\/croisiere-cabine\/\">En savoir plus<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<h3 class=\"wp-block-heading\">Notre promesse<\/h3>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<h4 class=\"scale-8 font-medium mb-1 wp-block-heading\">Cabines privatives<\/h4>\n\n\n\n<p>Cabines doubles standard, confortables et privatives avec salle de bain attenante<\/p>\n\n\n\n<h4 class=\"scale-8 font-medium mb-1 wp-block-heading\">Itin\u00e9raires organis\u00e9s<\/h4>\n\n\n\n<p>D\u00e9couvrez des destinations de renomm\u00e9e mondiale, la culture locale et des excursions avec nos itin\u00e9raires soigneusement s\u00e9lectionn\u00e9s<\/p>\n\n\n\n<h4 class=\"scale-8 font-medium mb-1 wp-block-heading\">Accessible<\/h4>\n\n\n\n<p>Une exp\u00e9rience abordable et intimiste sans avoir besoin de r\u00e9server un bateau entier ou d&rsquo;avoir de l&rsquo;exp\u00e9rience en navigation<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column\">\n<h4 class=\"scale-8 font-medium mb-1 wp-block-heading\">\u00c9quipage d&rsquo;experts<\/h4>\n\n\n\n<p>Profitez de notre \u00e9quipe professionnelle avec une solide connaissance locale et un service amical<\/p>\n\n\n\n<h4 class=\"scale-8 font-medium mb-1 wp-block-heading\">Repas en pension compl\u00e8te<\/h4>\n\n\n\n<p>D\u00e9gustez une cuisine fra\u00eeche et d\u00e9licieuse pr\u00e9par\u00e9e et servie quotidiennement<\/p>\n\n\n\n<h4 class=\"scale-8 font-medium mb-1 wp-block-heading\">Choisissez votre ambiance<\/h4>\n\n\n\n<p>D\u00e9tendez-vous sur le pont en discutant avec d&rsquo;autres voyageurs, faites du kayak ou de la plong\u00e9e avec palmes, masque et tuba depuis votre bateau ou profitez-en pour d\u00e9couvrir la r\u00e9gion.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"dyc-section dyc-section--double \">\n\t<div class=\"need_help_banner load_background\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/themes\/dyc\/assets\/dist\/theme\/img\/need-help.png\">\n\t\t<div class=\"banner__content-wrap\">\n\t\t\t<div class=\"banner__content d-flex justify-content-between\">\n\t\t\t\t<div class=\"banner__header\">\n\t\t\t\t\t\n\n<h3 class=\"wp-block-heading scale-6\">Besoin d&rsquo;aide&nbsp;?<\/h3>\n\n\n\n<p>Nous pouvons <strong>vous aider<\/strong> dans vos d\u00e9cisions.<\/p>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div><a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/contact\/\" class=\"push push--primary_white push--large\">Contactez-nous&nbsp;!<\/a><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">La v\u00e9ritable exp\u00e9rience #MyDreamYacht<\/h2>\n\n\n\n<p class=\"has-text-align-center\">D\u00e9couvrez sur\u00a0<a href=\"https:\/\/www.instagram.com\/dreamyacht.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0les exp\u00e9riences de clients ayant pass\u00e9 leurs vacances avec Dream Yacht.<\/p>\n\n\n\n<div class=\"wp-block-group dyc-section\"><div class=\"wp-block-group__inner-container\">\n<div class=\"dyc-section text-center \">\n    <div class=\"fake-instagram\" data-totalthumbs=\"20\">\n        <div class=\"top\">\n            <div class=\"image_main load_background debug\">\n                <div class=\"overlay_icon\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg>                <\/div>\n\n            <\/div>\n            <div class=\"review\">\n                <div class=\"fake-instagram__text\"><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Absolument incroyable ! Fred et Isabelle \u00e9taient si arrangeants et ont tant fait pour nous. La nourriture d&rsquo;Isabelle \u00e9tait incroyable. Merci beaucoup !<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Laura<\/h3><span class=\"fake-instagram__text__countries\">Exumas&nbsp;Cabin<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Excellent. Tr\u00e8s professionnel et excellent service !<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Thomas<\/h3><span class=\"fake-instagram__text__countries\">Antigua&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Juste ce dont nous avions besoin \u00e0 la sortie d&rsquo;une ann\u00e9e de confinement, pour voir de nouveaux endroits et se connecter avec la nature. Fortement recommand\u00e9 pour votre prochaine aventure \u00e0 la voile !<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Johan<\/h3><span class=\"fake-instagram__text__countries\">Saint-Martin&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Excellente croisi\u00e8re et tr\u00e8s bon s\u00e9jour. Skipper \u00e0 l&rsquo;\u00e9coute, tr\u00e8s agr\u00e9able et tr\u00e8s professionnel.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Maxime<\/h3><span class=\"fake-instagram__text__countries\">Guadeloupe&nbsp;Skippered<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Je viens de rentrer d&rsquo;une autre semaine de navigation fantastique depuis votre base de Pula et je tiens \u00e0 remercier toutes les personnes impliqu\u00e9es d&rsquo;avoir rendu cela possible dans un d\u00e9lai aussi court et sans aucun probl\u00e8me.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Mathias<\/h3><span class=\"fake-instagram__text__countries\">Croatie&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">La marina elle-m\u00eame est un point de d\u00e9part parfait avec de superbes installations ! Le Lagoon 42 \u00e9tait en bon \u00e9tat et le skipper \u00e9tait incroyable et connaissait tr\u00e8s bien la r\u00e9gion.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\"><\/h3><span class=\"fake-instagram__text__countries\">Espagne&nbsp;Skippered<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Quelle exp\u00e9rience INCROYABLE. Nous venons de rentrer d&rsquo;une semaine de location avec skipper depuis Corfou. Fini les s\u00e9jours \u00e0 l&rsquo;h\u00f4tel, d\u00e9sormais nous choisirons Dream Yacht et le bateau !<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">David<\/h3><span class=\"fake-instagram__text__countries\">Gr\u00e8ce&nbsp;Skippered<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Nous avons pass\u00e9 un moment g\u00e9nial en Polyn\u00e9sie fran\u00e7aise ! La nourriture \u00e9tait incroyable, notre capitaine et notre chef \u00e9taient parfaits et toute l&rsquo;exp\u00e9rience \u00e0 bord \u00e9tait un r\u00eave ! Nous avons h\u00e2te de r\u00e9server une autre croisi\u00e8re avec Dream Yacht.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Katie<\/h3><span class=\"fake-instagram__text__countries\">Tahiti&nbsp;Crewed Premium<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Superbe exp\u00e9rience de navigation aux \u00celes Vierges britanniques. Les bateaux \u00e9taient en tr\u00e8s bon \u00e9tat et le personnel \u00e9tait sympathique et serviable. Ayant travaill\u00e9 pour un certain nombre de compagnies de location au fil des ans, Dream Yacht est l&rsquo;une des meilleures.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Charlie<\/h3><span class=\"fake-instagram__text__countries\">\u00celes Vierges britanniques&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Nous avons eu la plus belle exp\u00e9rience d&rsquo;exploration des \u00eeles de l&rsquo;archipel. Je n&rsquo;aurais jamais imagin\u00e9 que \u00e7a serait si agr\u00e9able. Nous attendons avec impatience notre prochaine croisi\u00e8re dans les \u00eeles Ioniennes.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Vyautas<\/h3><span class=\"fake-instagram__text__countries\">Scandinavie&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">La base Dream Yacht \u00e0 La Paz a fourni un soutien professionnel comp\u00e9tent et un bateau bien entretenu. Nous avions pris un cuisinier \u00e0 bord et cela nous a permis de profiter pleinement de la croisi\u00e8re. Des vacances et une aventure en lien avec la nature.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Taiyoko<\/h3><span class=\"fake-instagram__text__countries\">Mexique&nbsp;Crewed Premium<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Tout le personnel \u00e9tait fantastique et a rendu notre s\u00e9jour inoubliable. Amical et accueillant, la nourriture \u00e9tait incroyable. Le service tout au long du voyage a toujours \u00e9t\u00e9 de premi\u00e8re classe !<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Tommy<\/h3><span class=\"fake-instagram__text__countries\">Tha\u00eflande&nbsp;Cabin<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Je recommande absolument. Service et mise en place parfaits. Nous louerons \u00e0 nouveau et recommanderons Dream Yacht Charter \u00e0 tout moment.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Zahradnik<\/h3><span class=\"fake-instagram__text__countries\">Turquie&nbsp;Cabin<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Je viens de rentrer de 3 semaines de navigation incroyable avec ma famille sur l&rsquo;un de vos catamarans en Sardaigne. Je voudrais exprimer mes remerciements \u00e0 notre skipper Simone et \u00e0 Daniela, notre h\u00f4tesse.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Giles<\/h3><span class=\"fake-instagram__text__countries\">Sardaigne&nbsp;Skippered<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Pour une premi\u00e8re croisi\u00e8re en tant que skipper, la M\u00e9diterran\u00e9e c&rsquo;est super. Le service Dream Yacht Charter l&rsquo;est aussi !<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Thomas<\/h3><span class=\"fake-instagram__text__countries\">France&nbsp;No Product Type Selected<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Nous avons fait un voyage incroyable et nous nous sommes fianc\u00e9s le premier soir\u00a0! Merci de nous avoir pr\u00e9par\u00e9s cette croisi\u00e8re et de nous avoir donn\u00e9 une formation approfondie mais facile \u00e0 suivre\u00a0: cela nous a donn\u00e9 confiance pour notre prochaine exp\u00e9rience.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">George<\/h3><span class=\"fake-instagram__text__countries\">Australie&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">L&rsquo;exp\u00e9rience \u00e0 bord \u00e9tait bien au-del\u00e0 de nos attentes. Isabelle a fourni des repas exceptionnels \u00e0 trois plats. Thomas \u00e9tait un excellent skipper, toujours \u00e0 l&rsquo;\u00e9coute de nos besoins. Merci \u00e0 tous !<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Spira<\/h3><span class=\"fake-instagram__text__countries\">Nouvelle-Cal\u00e9donie&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Encore une fois une nouvelle croisi\u00e8re fantastique avec un super \u00e9quipage. Merci encore \u00e0 un super capitaine et un grand cuisinier. C&rsquo;\u00e9tait fantastique.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Connie<\/h3><span class=\"fake-instagram__text__countries\">Seychelles&nbsp;Crewed Premium<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">C&rsquo;est toujours un plaisir de naviguer avec Dream Yacht au Royaume-Uni. Super \u00e9quipe, supers bateaux, super navigation. Ils sont tr\u00e8s flexibles et travaillent dur pour faire de votre voyage un succ\u00e8s.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Derek<\/h3><span class=\"fake-instagram__text__countries\">Bretagne&nbsp;Cabin<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\">Des spots inoubliables pour faire du snorkeling et des plages magnifiques. \u00c9quipage tr\u00e8s exp\u00e9riment\u00e9. Je recommande fortement.<\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\">Simone<\/h3><span class=\"fake-instagram__text__countries\">No Country Selected&nbsp;Bareboat<\/div><div class=\"review-item d-none\"><h2 class=\"fake-instagram__text__title scale-5 mb-3\"><\/h2><h3 class=\"fake-instagram__text__name scale-7 mb-05\"><\/h3><span class=\"fake-instagram__text__countries\">No Country Selected&nbsp;Cabin<\/div><\/div>            <\/div>\n        <\/div>\n        <div class=\"thumbnails\">\n            <div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Thebenjenkins-Instagram-27th-Sep-2022-15_16-UTC-192x192.jpeg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Thebenjenkins-Instagram-27th-Sep-2022-15_16-UTC-672x672.jpeg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/287225451_145693837826620_121055401638420822_n-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/287225451_145693837826620_121055401638420822_n-672x840.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Croatia2023-VoileEvasion-12-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Croatia2023-VoileEvasion-12-672x354.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/292622928_1659323207772084_4894130388229818820_n-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/292622928_1659323207772084_4894130388229818820_n-672x840.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Elliot_stunts-Instagram-6th-Oct-2022-17_46-UTC-192x192.jpeg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Elliot_stunts-Instagram-6th-Oct-2022-17_46-UTC.jpeg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Ourdays.de-Instagram-14th-Oct-2022-17_16-UTC-192x192.jpeg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Ourdays.de-Instagram-14th-Oct-2022-17_16-UTC-672x839.jpeg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Croatia2023-VoileEvasion-84-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Croatia2023-VoileEvasion-84-672x447.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/308595396_150699687641088_5365559750700909037_n-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/308595396_150699687641088_5365559750700909037_n-672x840.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/10\/Antigua-and-Barbuda-1487-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/10\/Antigua-and-Barbuda-1487-672x448.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/ourdays_seychelles23_full-008-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/ourdays_seychelles23_full-008-672x840.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Kevin.ruffing-Instagram-26th-Sep-2022-18_31-UTC-192x192.jpeg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Kevin.ruffing-Instagram-26th-Sep-2022-18_31-UTC-672x840.jpeg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Croatia2023-VoileEvasion-08-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/Croatia2023-VoileEvasion-08-672x354.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/ourdays_Exumas_full-044-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/ourdays_Exumas_full-044-672x378.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/08\/P_cabin_charter_15-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/08\/P_cabin_charter_15-672x840.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/20230904_121008-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/09\/20230904_121008-672x504.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/07\/DYC_ourdays_cuba_web-41-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/07\/DYC_ourdays_cuba_web-41-672x448.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/02\/ourdays_sardinia_set1_full-31-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/02\/ourdays_sardinia_set1_full-31-672x672.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/09\/ourdays_sardinia_set2_full-14-2048x1152-1-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2022\/09\/ourdays_sardinia_set2_full-14-2048x1152-1-672x378.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div><div class=\"thumbnail load_background d-none debug\" data-background=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/07\/ourdays_corfu_lefkas_web-9-192x192.jpg\"data-img=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2023\/07\/ourdays_corfu_lefkas_web-9-672x840.jpg\"><div class=\"overlay_icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\"><path style=\"stroke:none;fill-rule:nonzero;fill:#fff;fill-opacity:1\" d=\"M9 1.621c2.402 0 2.688.012 3.637.055 2.441.11 3.578 1.265 3.691 3.687.043.95.05 1.235.05 3.637 0 2.406-.007 2.688-.05 3.637-.113 2.418-1.25 3.578-3.691 3.691-.95.043-1.23.05-3.637.05-2.402 0-2.688-.007-3.637-.05-2.445-.113-3.578-1.277-3.687-3.691-.047-.95-.055-1.235-.055-3.637s.012-2.688.055-3.637c.11-2.422 1.246-3.578 3.687-3.687.95-.043 1.235-.055 3.637-.055ZM9 0C6.555 0 6.25.012 5.29.055 2.02.203.202 2.015.054 5.289.012 6.25 0 6.555 0 9s.012 2.75.055 3.71c.148 3.27 1.96 5.087 5.234 5.235C6.25 17.988 6.555 18 9 18s2.75-.012 3.71-.055c3.267-.148 5.087-1.96 5.235-5.234C17.988 11.75 18 11.445 18 9s-.012-2.75-.055-3.71c-.144-3.267-1.96-5.087-5.234-5.235C11.75.012 11.445 0 9 0Zm0 4.379A4.623 4.623 0 0 0 4.379 9 4.62 4.62 0 1 0 9 4.379ZM9 12a3 3 0 1 1 .002-6.002A3 3 0 0 1 9 12Zm4.805-8.883a1.081 1.081 0 1 0-.002 2.162 1.081 1.081 0 0 0 .002-2.162Zm0 0\"\/><\/svg><\/div><\/div>        <\/div>\n    <\/div><!-- .fake-instagram -->\n<\/div>\n\n\n<\/div><\/div>\n\n\n\n\t\t\t\t<div class=\"row justify-content-center pt-12 pb-12 destinations-blog\">\n\t\t\t\t\t<div class=\"col-12 col-sm-8 col-md-5 text-center text-md-left mb-5 mb-md-0\">\n\t\t\t\t\t\t<h2 class=\"scale-0 font-normal text-dark-green\">\n\t\t\t\t\t\t\tQuoi de neuf?\t\t\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"editor p-normal mt-3  text-dark-green\">\n\t\t\t\t\t\t\t\t<span style=\"font-weight: 400;\">Restez inform\u00e9 des actualit\u00e9s et des \u00e9v\u00e9nements ou profitez d&rsquo;un peu d&rsquo;inspiration pour votre prochaine croisi\u00e8re et obtenez des conseils utiles en lisant nos derniers articles de blogs.<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/\" class=\"push push--primary push--large mt-3 mt-md-4\">Aller sur le blog<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"col-12 col-md-6 ml-md-auto\">\n\t\t\t\t\t\t<div class=\"front-page__section-slider\">\n\t\t\t\t\t\t\t<div class=\"d-block d-sm-flex justify-space-between align-items-top\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"card--blog card mb-4 mb-sm-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__img-wrap \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"283\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-424x283.jpg\" class=\"attachment-img-424 size-img-424 wp-post-image\" alt=\"Martinique Les Anses-d&#039;Arlet Bridge and coastal town view\" srcset=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-424x283.jpg 424w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-1536x1024.jpg 1536w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-2048x1365.jpg 2048w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-1920x1280.jpg 1920w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-1272x848.jpg 1272w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-912x608.jpg 912w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-672x448.jpg 672w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-514x343.jpg 514w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-324x216.jpg 324w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/08\/Martinique-Les-Anses-dArlet-300x200.jpg 300w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__content mt-1\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__footer mt-auto\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"scale-12 font-normal mb-2\">\n\t<time class=\"text-dark-green\" datetime=\"2026-08-10T14:40:24+00:00\">\n\t\t10 Ao\u00fbt 2026,\n\t<\/time>\n\t<span class=\"post-categories text-brown\">\n\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/actualites\/\" rel=\"category tag\">Actualit\u00e9s<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/caraibes\/\" rel=\"category tag\">Cara\u00efbes<\/a>\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/dream-yacht-martinique-remporte-le-prix-travellers-choice-2026-de-tripadvisor\/\" class=\"text-dark-green\">Dream Yacht Martinique remporte le prix \u00ab Travellers\u2019 Choice \u00bb 2026 de TripAdvisor<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"card--blog card mb-4 mb-sm-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__img-wrap \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"284\" src=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-424x284.jpg\" class=\"attachment-img-424 size-img-424 wp-post-image\" alt=\"Sociial gathering in the forward cockpit of the sailing catamaran\" srcset=\"https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-424x284.jpg 424w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-1536x1028.jpg 1536w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-2048x1371.jpg 2048w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-1920x1285.jpg 1920w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-1272x851.jpg 1272w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-912x610.jpg 912w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-672x450.jpg 672w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-514x344.jpg 514w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-324x217.jpg 324w, https:\/\/www.dreamyachtcharter.com\/wp-content\/uploads\/2026\/07\/Catamaran-from-above-forward-cockpit-300x201.jpg 300w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__content mt-1\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__footer mt-auto\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"scale-12 font-normal mb-2\">\n\t<time class=\"text-dark-green\" datetime=\"2026-07-24T16:54:00+00:00\">\n\t\t24 Juillet 2026,\n\t<\/time>\n\t<span class=\"post-categories text-brown\">\n\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/croisiere-a-la-cabine\/\" rel=\"category tag\">Croisi\u00e8re \u00e0 la cabine<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/caraibes\/\" rel=\"category tag\">Cara\u00efbes<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/caraibes\/\" rel=\"category tag\">Cara\u00efbes<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/location-de-bateau\/\" rel=\"category tag\">Location de bateau<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/croisiere-avec-equipage\/\" rel=\"category tag\">Croisi\u00e8re avec \u00e9quipage<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/croisiere-a-la-cabine\/\" rel=\"category tag\">Croisi\u00e8re \u00e0 la cabine<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/croisiere-avec-equipage\/\" rel=\"category tag\">Croisi\u00e8re avec \u00e9quipage<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/location-avec-skipper\/\" rel=\"category tag\">Location avec skipper<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/location-de-bateau\/\" rel=\"category tag\">Location de bateau<\/a>, <a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/category\/location-avec-skipper\/\" rel=\"category tag\">Location avec skipper<\/a>\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"card__title scale-5 font-normal\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.dreamyachtcharter.com\/fr\/blog\/vacances-aux-iles-vierges-britanniques-sans-experience-de-la-voile-les-meilleures-options-de-location-de-bateau-pour-les-debutants\/\" class=\"text-dark-green\">Vacances aux \u00celes Vierges britanniques sans exp\u00e9rience de la voile : les meilleures options de location de bateau pour les d\u00e9butants<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\n\n<div class=\"dyc-section text-center \">\n\t<a class=\"push push--secondary push--large push--icon d-inline-flex\" href=\"#act\">\n\t\tTypes de locations disponibles\t<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Paz est situ\u00e9e \u00e0 l&rsquo;extr\u00e9mit\u00e9 sud de la p\u00e9ninsule de Basse Californie, s\u00e9par\u00e9e du Mexique par la fascinante mer de Cortez, \u00e9galement connue sous le nom de golfe de &hellip;<\/p>\n","protected":false},"featured_media":409,"parent":10715,"menu_order":0,"template":"","highlight":[214,212,213],"class_list":["post-6800","destination","type-destination","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dreamyachtcharter.com\/fr\/wp-json\/wp\/v2\/destination\/6800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dreamyachtcharter.com\/fr\/wp-json\/wp\/v2\/destination"}],"about":[{"href":"https:\/\/www.dreamyachtcharter.com\/fr\/wp-json\/wp\/v2\/types\/destination"}],"up":[{"embeddable":true,"href":"https:\/\/www.dreamyachtcharter.com\/fr\/wp-json\/wp\/v2\/destination\/10715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dreamyachtcharter.com\/fr\/wp-json\/wp\/v2\/media\/409"}],"wp:attachment":[{"href":"https:\/\/www.dreamyachtcharter.com\/fr\/wp-json\/wp\/v2\/media?parent=6800"}],"wp:term":[{"taxonomy":"highlight","embeddable":true,"href":"https:\/\/www.dreamyachtcharter.com\/fr\/wp-json\/wp\/v2\/highlight?post=6800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}